{"id":10215,"date":"2018-04-27T08:19:12","date_gmt":"2018-04-27T08:19:12","guid":{"rendered":"https:\/\/dev.comet-spa.com\/orchard-spraying-agriculture\/"},"modified":"2019-01-18T17:20:07","modified_gmt":"2019-01-18T17:20:07","slug":"atomizzatori","status":"publish","type":"page","link":"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/","title":{"rendered":"Atomizzatori"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#e7e4e2;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"margin-top:10px;margin-bottom:10px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\"><\/style><div class=\"fusion-title title fusion-title-1 fusion-title-center fusion-title-text fusion-title-size-two\" style=\"margin-top:0px;margin-right:0px;margin-bottom:30px;margin-left:0px;\"><div class=\"title-sep-container title-sep-container-left\"><div class=\"title-sep sep-single sep-solid\" style=\"border-color:#4eae33;\"><\/div><\/div><span class=\"awb-title-spacer\"><\/span><h2 class=\"title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:34;line-height:1.47;\">ATOMIZZATORI<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-single sep-solid\" style=\"border-color:#4eae33;\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#e7e4e2;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"margin-top:10px;margin-bottom:10px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\">.fusion-portfolio-wrapper#fusion-portfolio-1 .fusion-portfolio-content{  text-align: center; }<\/style><div class=\"fusion-recent-works fusion-portfolio-element fusion-portfolio fusion-portfolio-1 fusion-portfolio-grid fusion-portfolio-paging-load-more-button fusion-portfolio-three fusion-portfolio-unboxed fusion-portfolio-text fusion-portfolio-equal-heights fusion-portfolio-rollover\" data-id=\"-rw-1\" data-columns=\"three\"><style type=\"text\/css\">.fusion-portfolio-1 .fusion-portfolio-wrapper .fusion-col-spacing{padding:10px;}<\/style><div class=\"fusion-portfolio-wrapper\" id=\"fusion-portfolio-1\" data-picturesize=\"auto\" data-pages=\"0\" style=\"margin:-10px;\"><article id=\"portfolio-1-post-18634\" class=\"fusion-portfolio-post cat-other-applications-agri-it medium-pressure-diaphragm-pumps cat-wheel-barrows-it cat-orchard-spraying-it fusion-col-spacing post-18634\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/03\/p40-20FEATURED.png\" class=\"attachment-full size-full wp-post-image\" alt=\"p 40-20\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/03\/p40-20FEATURED-200x182.png 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/03\/p40-20FEATURED-400x364.png 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/03\/p40-20FEATURED.png 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-40-20\/?portfolioCats=515%2C515\">P 40\/20<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-40-20\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tP 40\/20\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-40-20\/?portfolioCats=515%2C515\" aria-label=\"P 40\/20\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-40-20\/?portfolioCats=515%2C515\">P 40\/20<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7278\" class=\"fusion-portfolio-post cat-other-applications-agri-it medium-pressure-diaphragm-pumps cat-wheel-barrows-it cat-orchard-spraying-it fusion-col-spacing post-7278\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/p_36_10.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet P 36\/10\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/p_36_10-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/p_36_10-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/p_36_10.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-36-10-36-15\/?portfolioCats=515%2C515\">P 36\/10 -36\/15<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-36-10-36-15\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tP 36\/10 -36\/15\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-36-10-36-15\/?portfolioCats=515%2C515\" aria-label=\"P 36\/10 -36\/15\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-36-10-36-15\/?portfolioCats=515%2C515\">P 36\/10 -36\/15<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7294\" class=\"fusion-portfolio-post cat-spraying-pumps-it cat-wheel-barrows-it medium-pressure-diaphragm-pumps cat-orchard-spraying-it fusion-col-spacing post-7294\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/mp_30.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"mp 30 Comet Agricultural Pumps\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/mp_30-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/mp_30-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/mp_30.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/mp-20-30\/?portfolioCats=515%2C515\">MP 20 &#8211; 30<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/mp-20-30\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tMP 20 &#8211; 30\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/mp-20-30\/?portfolioCats=515%2C515\" aria-label=\"MP 20 &#8211; 30\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/mp-20-30\/?portfolioCats=515%2C515\">MP 20 &#8211; 30<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7284\" class=\"fusion-portfolio-post cat-wheel-barrows-it medium-pressure-diaphragm-pumps cat-orchard-spraying-it fusion-col-spacing post-7284\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/p_48_ap.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet P 48 AP\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/p_48_ap-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/p_48_ap-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/p_48_ap.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-48-p-48-ap\/?portfolioCats=515%2C515\">P 48 &#8211; P 48 AP<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-48-p-48-ap\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tP 48 &#8211; P 48 AP\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-48-p-48-ap\/?portfolioCats=515%2C515\" aria-label=\"P 48 &#8211; P 48 AP\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/p-48-p-48-ap\/?portfolioCats=515%2C515\">P 48 &#8211; P 48 AP<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7297\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it cat-wheel-barrows-it cat-orchard-spraying-it high-pressure-diaphragm-pumps aps-series-it fusion-col-spacing post-7297\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_31_41.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet APS 31 - 41\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_31_41-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_31_41-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_31_41.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-31-41\/?portfolioCats=515%2C515\">APS 31 &#8211; 41<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-31-41\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tAPS 31 &#8211; 41\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-31-41\/?portfolioCats=515%2C515\" aria-label=\"APS 31 &#8211; 41\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-31-41\/?portfolioCats=515%2C515\">APS 31 &#8211; 41<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7301\" class=\"fusion-portfolio-post cat-spraying-pumps-it cat-wheel-barrows-it cat-orchard-spraying-it high-pressure-diaphragm-pumps aps-series-it fusion-col-spacing post-7301\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_51.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet APS 51\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_51-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_51-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_51.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-51\/?portfolioCats=515%2C515\">APS 51<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-51\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tAPS 51\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-51\/?portfolioCats=515%2C515\" aria-label=\"APS 51\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-51\/?portfolioCats=515%2C515\">APS 51<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7309\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it cat-wheel-barrows-it cat-orchard-spraying-it high-pressure-diaphragm-pumps aps-series-it fusion-col-spacing post-7309\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_61_71.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet APS 61 -71\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_61_71-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_61_71-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_61_71.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-61-71\/?portfolioCats=515%2C515\">APS 61 &#8211; 71<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-61-71\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tAPS 61 &#8211; 71\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-61-71\/?portfolioCats=515%2C515\" aria-label=\"APS 61 &#8211; 71\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-61-71\/?portfolioCats=515%2C515\">APS 61 &#8211; 71<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7313\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it high-pressure-diaphragm-pumps cat-orchard-spraying-it aps-series-it fusion-col-spacing post-7313\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_96.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet APS 96\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_96-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_96-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_96.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-96\/?portfolioCats=515%2C515\">APS 96<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-96\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tAPS 96\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-96\/?portfolioCats=515%2C515\" aria-label=\"APS 96\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-96\/?portfolioCats=515%2C515\">APS 96<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7326\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it cat-orchard-spraying-it high-pressure-diaphragm-pumps aps-series-it fusion-col-spacing post-7326\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_145.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet APS 145\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_145-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_145-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_145.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-145\/?portfolioCats=515%2C515\">APS 145<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-145\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tAPS 145\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-145\/?portfolioCats=515%2C515\" aria-label=\"APS 145\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-145\/?portfolioCats=515%2C515\">APS 145<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7317\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it cat-orchard-spraying-it high-pressure-diaphragm-pumps aps-series-it fusion-col-spacing post-7317\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_101_121.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet APS 101 - 121\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_101_121-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_101_121-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_101_121.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-101-121\/?portfolioCats=515%2C515\">APS 101 &#8211; 121<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-101-121\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tAPS 101 &#8211; 121\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-101-121\/?portfolioCats=515%2C515\" aria-label=\"APS 101 &#8211; 121\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-101-121\/?portfolioCats=515%2C515\">APS 101 &#8211; 121<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7334\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it cat-orchard-spraying-it high-pressure-diaphragm-pumps aps-series-it fusion-col-spacing post-7334\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_141_166.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet APS 141 -166\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_141_166-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_141_166-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/aps_141_166.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-141-166\/?portfolioCats=515%2C515\">APS 141 -166<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-141-166\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tAPS 141 -166\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-141-166\/?portfolioCats=515%2C515\" aria-label=\"APS 141 -166\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/aps-141-166\/?portfolioCats=515%2C515\">APS 141 -166<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7337\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it cat-orchard-spraying-it high-pressure-diaphragm-pumps ids-series-it fusion-col-spacing post-7337\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_960.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet IDS 960\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_960-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_960-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_960.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-960\/?portfolioCats=515%2C515\">IDS 960<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-960\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tIDS 960\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-960\/?portfolioCats=515%2C515\" aria-label=\"IDS 960\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-960\/?portfolioCats=515%2C515\">IDS 960<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7354\" class=\"fusion-portfolio-post cat-spraying-pumps-it cat-orchard-spraying-it high-pressure-diaphragm-pumps ids-series-it fusion-col-spacing post-7354\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1000.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet IDS 1000\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1000-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1000-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1000.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1000\/?portfolioCats=515%2C515\">IDS 1000<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1000\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tIDS 1000\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1000\/?portfolioCats=515%2C515\" aria-label=\"IDS 1000\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1000\/?portfolioCats=515%2C515\">IDS 1000<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7370\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it cat-orchard-spraying-it high-pressure-diaphragm-pumps ids-series-it fusion-col-spacing post-7370\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1201_1401.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet IDS 1201 - 1401\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1201_1401-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1201_1401-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1201_1401.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1201-1401\/?portfolioCats=515%2C515\">IDS 1201 &#8211; 1401<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1201-1401\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tIDS 1201 &#8211; 1401\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1201-1401\/?portfolioCats=515%2C515\" aria-label=\"IDS 1201 &#8211; 1401\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1201-1401\/?portfolioCats=515%2C515\">IDS 1201 &#8211; 1401<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-20018\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it cat-orchard-spraying-it high-pressure-diaphragm-pumps ids-series-it fusion-col-spacing post-20018\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/05\/IDS-HD-1701featured.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/05\/IDS-HD-1701featured-200x182.png 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/05\/IDS-HD-1701featured-400x364.png 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/05\/IDS-HD-1701featured.png 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1701-2001-hd\/?portfolioCats=515%2C515\">IDS 1701 &#8211; 2001 HD<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1701-2001-hd\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tIDS 1701 &#8211; 2001 HD\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1701-2001-hd\/?portfolioCats=515%2C515\" aria-label=\"IDS 1701 &#8211; 2001 HD\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1701-2001-hd\/?portfolioCats=515%2C515\">IDS 1701 &#8211; 2001 HD<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7361\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it cat-orchard-spraying-it high-pressure-diaphragm-pumps ids-series-it fusion-col-spacing post-7361\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1400.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet IDS 1400\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1400-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1400-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1400.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1400\/?portfolioCats=515%2C515\">IDS 1400<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1400\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tIDS 1400\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1400\/?portfolioCats=515%2C515\" aria-label=\"IDS 1400\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1400\/?portfolioCats=515%2C515\">IDS 1400<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-19994\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it cat-orchard-spraying-it high-pressure-diaphragm-pumps ids-series-it fusion-col-spacing post-19994\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/05\/POMPA-IDS-2200_2600-HDfeatured.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/05\/POMPA-IDS-2200_2600-HDfeatured-200x182.png 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/05\/POMPA-IDS-2200_2600-HDfeatured-400x364.png 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2020\/05\/POMPA-IDS-2200_2600-HDfeatured.png 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-2200-2600-hd\/?portfolioCats=515%2C515\">IDS 2200 &#8211; 2600 HD<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-2200-2600-hd\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tIDS 2200 &#8211; 2600 HD\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-2200-2600-hd\/?portfolioCats=515%2C515\" aria-label=\"IDS 2200 &#8211; 2600 HD\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-2200-2600-hd\/?portfolioCats=515%2C515\">IDS 2200 &#8211; 2600 HD<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7374\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it high-pressure-diaphragm-pumps cat-orchard-spraying-it ids-series-it fusion-col-spacing post-7374\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1501_1701_2001.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet IDS 1501 - 1701 - 2001\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1501_1701_2001-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1501_1701_2001-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_1501_1701_2001.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1501-1701-2001\/?portfolioCats=515%2C515\">IDS 1501 &#8211; 1701 &#8211; 2001<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1501-1701-2001\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tIDS 1501 &#8211; 1701 &#8211; 2001\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1501-1701-2001\/?portfolioCats=515%2C515\" aria-label=\"IDS 1501 &#8211; 1701 &#8211; 2001\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-1501-1701-2001\/?portfolioCats=515%2C515\">IDS 1501 &#8211; 1701 &#8211; 2001<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7364\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-spraying-pumps-it cat-orchard-spraying-it high-pressure-diaphragm-pumps ids-series-it fusion-col-spacing post-7364\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_2200_2600.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet IDS 2200 - 2600\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_2200_2600-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_2200_2600-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ids_2200_2600.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-2200-2600\/?portfolioCats=515%2C515\">IDS 2200 &#8211; 2600<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-2200-2600\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tIDS 2200 &#8211; 2600\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-2200-2600\/?portfolioCats=515%2C515\" aria-label=\"IDS 2200 &#8211; 2600\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ids-2200-2600\/?portfolioCats=515%2C515\">IDS 2200 &#8211; 2600<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7379\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-other-applications-agri-it cat-boom-spraying-it cat-wheel-barrows-it cat-orchard-spraying-it high-pressure-piston-pumps ya-series-it fusion-col-spacing post-7379\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ya_65_75.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet YA 65 - 75\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ya_65_75-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ya_65_75-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ya_65_75.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ya-65-75\/?portfolioCats=515%2C515\">YA 65 &#8211; 75<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ya-65-75\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tYA 65 &#8211; 75\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ya-65-75\/?portfolioCats=515%2C515\" aria-label=\"YA 65 &#8211; 75\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ya-65-75\/?portfolioCats=515%2C515\">YA 65 &#8211; 75<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7390\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-other-applications-agri-it cat-boom-spraying-it cat-wheel-barrows-it cat-orchard-spraying-it high-pressure-piston-pumps yb-series-it fusion-col-spacing post-7390\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/yb_75.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet YB 75\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/yb_75-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/yb_75-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/yb_75.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/yb-75\/?portfolioCats=515%2C515\">YB 75<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/yb-75\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tYB 75\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/yb-75\/?portfolioCats=515%2C515\" aria-label=\"YB 75\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/yb-75\/?portfolioCats=515%2C515\">YB 75<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7383\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-other-applications-agri-it cat-boom-spraying-it cat-orchard-spraying-it high-pressure-piston-pumps ya-series-it fusion-col-spacing post-7383\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ya_130_150.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet YA 130 - 150\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ya_130_150-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ya_130_150-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/ya_130_150.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ya-130-150\/?portfolioCats=515%2C515\">YA 130 &#8211; 150<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ya-130-150\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tYA 130 &#8211; 150\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ya-130-150\/?portfolioCats=515%2C515\" aria-label=\"YA 130 &#8211; 150\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/ya-130-150\/?portfolioCats=515%2C515\">YA 130 &#8211; 150<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><article id=\"portfolio-1-post-7393\" class=\"fusion-portfolio-post high-pressure-pumps-it cat-other-applications-agri-it cat-boom-spraying-it cat-orchard-spraying-it high-pressure-piston-pumps yb-series-it fusion-col-spacing post-7393\"><div class=\"fusion-portfolio-content-wrapper\" style=\"border:none;\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t  <img width=\"472\" height=\"430\" src=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/yb_150.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Comet YB 150\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/yb_150-200x182.jpg 200w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/yb_150-400x364.jpg 400w, https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/03\/yb_150.jpg 472w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 413px, (min-width: 732px) 620px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/yb-150\/?portfolioCats=515%2C515\">YB 150<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/yb-150\/?portfolioCats=515%2C515\">\n\t\t\t\t\t\tYB 150\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/yb-150\/?portfolioCats=515%2C515\" aria-label=\"YB 150\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-portfolio-content\"><h2 class=\"fusion-post-title\"><a href=\"https:\/\/dev.comet-spa.com\/it\/products-category\/yb-150\/?portfolioCats=515%2C515\">YB 150<\/a><\/h2><div class=\"fusion-post-content\"><\/div><\/div><\/div><\/article><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":11300,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Atomizzatori - Comet Spa<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atomizzatori - Comet Spa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/\" \/>\n<meta property=\"og:site_name\" content=\"Comet Spa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Cometgroupspa\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-18T17:20:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/\",\"url\":\"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/\",\"name\":\"Atomizzatori - Comet Spa\",\"isPartOf\":{\"@id\":\"https:\/\/dev.comet-spa.com\/it\/#website\"},\"datePublished\":\"2018-04-27T08:19:12+00:00\",\"dateModified\":\"2019-01-18T17:20:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.comet-spa.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agricoltura\",\"item\":\"https:\/\/dev.comet-spa.com\/it\/agricoltura\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Applicazioni Agricoltura\",\"item\":\"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Atomizzatori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.comet-spa.com\/it\/#website\",\"url\":\"https:\/\/dev.comet-spa.com\/it\/\",\"name\":\"Comet Spa\",\"description\":\"Agricultural Industrial e Cleaning Pumps\",\"publisher\":{\"@id\":\"https:\/\/dev.comet-spa.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.comet-spa.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.comet-spa.com\/it\/#organization\",\"name\":\"Comet Spa\",\"url\":\"https:\/\/dev.comet-spa.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dev.comet-spa.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/02\/logo.png\",\"contentUrl\":\"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/02\/logo.png\",\"width\":300,\"height\":75,\"caption\":\"Comet Spa\"},\"image\":{\"@id\":\"https:\/\/dev.comet-spa.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Cometgroupspa\",\"https:\/\/www.linkedin.com\/company\/comet-s-p-a-\",\"http:\/\/www.youtube.com\/channel\/UCef353b7MfpEv6dCix0o2lw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atomizzatori - Comet Spa","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Atomizzatori - Comet Spa","og_url":"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/","og_site_name":"Comet Spa","article_publisher":"https:\/\/www.facebook.com\/Cometgroupspa","article_modified_time":"2019-01-18T17:20:07+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/","url":"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/","name":"Atomizzatori - Comet Spa","isPartOf":{"@id":"https:\/\/dev.comet-spa.com\/it\/#website"},"datePublished":"2018-04-27T08:19:12+00:00","dateModified":"2019-01-18T17:20:07+00:00","breadcrumb":{"@id":"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/atomizzatori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.comet-spa.com\/it\/"},{"@type":"ListItem","position":2,"name":"Agricoltura","item":"https:\/\/dev.comet-spa.com\/it\/agricoltura\/"},{"@type":"ListItem","position":3,"name":"Applicazioni Agricoltura","item":"https:\/\/dev.comet-spa.com\/it\/agricoltura\/applicazioni-agricoltura\/"},{"@type":"ListItem","position":4,"name":"Atomizzatori"}]},{"@type":"WebSite","@id":"https:\/\/dev.comet-spa.com\/it\/#website","url":"https:\/\/dev.comet-spa.com\/it\/","name":"Comet Spa","description":"Agricultural Industrial e Cleaning Pumps","publisher":{"@id":"https:\/\/dev.comet-spa.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.comet-spa.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/dev.comet-spa.com\/it\/#organization","name":"Comet Spa","url":"https:\/\/dev.comet-spa.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dev.comet-spa.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/02\/logo.png","contentUrl":"https:\/\/dev.comet-spa.com\/wp-content\/uploads\/2018\/02\/logo.png","width":300,"height":75,"caption":"Comet Spa"},"image":{"@id":"https:\/\/dev.comet-spa.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Cometgroupspa","https:\/\/www.linkedin.com\/company\/comet-s-p-a-","http:\/\/www.youtube.com\/channel\/UCef353b7MfpEv6dCix0o2lw"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/dev.comet-spa.com\/it\/wp-json\/wp\/v2\/pages\/10215"}],"collection":[{"href":"https:\/\/dev.comet-spa.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.comet-spa.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.comet-spa.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.comet-spa.com\/it\/wp-json\/wp\/v2\/comments?post=10215"}],"version-history":[{"count":0,"href":"https:\/\/dev.comet-spa.com\/it\/wp-json\/wp\/v2\/pages\/10215\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/dev.comet-spa.com\/it\/wp-json\/wp\/v2\/pages\/11300"}],"wp:attachment":[{"href":"https:\/\/dev.comet-spa.com\/it\/wp-json\/wp\/v2\/media?parent=10215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}